{"id":8182,"date":"2024-09-02T04:55:17","date_gmt":"2024-09-01T20:55:17","guid":{"rendered":"https:\/\/hongkongwebdesign.company\/?post_type=portfolio&#038;p=8182"},"modified":"2024-09-19T02:10:07","modified_gmt":"2024-09-18T18:10:07","slug":"living-plus-web-design","status":"publish","type":"portfolio","link":"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/","title":{"rendered":"\u4f4f+\u5c45\u5ba4"},"content":{"rendered":"<div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-0  el_before_av_one_fourth  avia-builder-el-first   container_wrap fullsize'  ><div  class='avia-slideshow av-iiqk1d-e933b5f7d21f1fe5435736bbbc9048c6 avia-slideshow-no scaling av_slideshow_full avia-slide-slider av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied  image_no_stretch avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 21.484375%;'><li  class='avia-slideshow-slide av-iiqk1d-e933b5f7d21f1fe5435736bbbc9048c6__0  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img fetchpriority=\"high\" class=\"wp-image-7812 avia-img-lazy-loading-not-7812\"  src='https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/hong-kong-company-web-design-website-banner1.avif' width='2560' height='550' title='hong-kong-company-web-design-website-banner1' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><\/ul><\/div><\/div><div id='after_full_slider_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-8182'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-dsc2zl-788de1b080377b9f40cb9e33d1b4ae57 av_one_fourth  avia-builder-el-1  el_after_av_slideshow_full  el_before_av_three_fourth  avia-builder-el-first  first flex_column_div  '     ><section  class='av_textblock_section av-c8d4ep-068cf03cf57e7bd242a5455fcd927e9d '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>\u8bbe\u8ba1\u8be6\u60c5<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ayt8wx-a93601c3b6ef1f8da3a8fc711768dd7d\">\n#top .hr.hr-invisible.av-ayt8wx-a93601c3b6ef1f8da3a8fc711768dd7d{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-ayt8wx-a93601c3b6ef1f8da3a8fc711768dd7d hr-invisible  avia-builder-el-3  el_after_av_textblock  el_before_av_icon_box '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<article  class='iconbox iconbox_left av-94yhox-6d4275ce6a854324898ba5332a880164  avia-builder-el-4  el_after_av_hr  el_before_av_icon_box '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: \u4f4f+\u5c45\u5ba4\"><div class='iconbox_icon heading-color avia-svg-icon avia-font-svg_entypo-fontello' data-av_icon='\ue80a' data-av_iconfont='entypo-fontello'  ><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >\u4f4f+\u5c45\u5ba4<\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><br \/>\n<article  class='iconbox iconbox_left av-7xszrl-b4fdb78dd97d842459c819d0f6eafaf9  avia-builder-el-5  el_after_av_icon_box  el_before_av_icon_box '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: www.livingplus.com.hk\"><div class='iconbox_icon heading-color avia-svg-icon avia-font-svg_entypo-fontello' data-av_icon='\ue8ab' data-av_iconfont='entypo-fontello'  ><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >www.livingplus.com.hk<\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><br \/>\n<article  class='iconbox iconbox_left av-5d7g1t-a7ffc39c537667e21e27c2e4e1e074ae  avia-builder-el-6  el_after_av_icon_box  avia-builder-el-last '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: \u7f51\u9875\u8bbe\u8ba1\u3001\u624b\u673a\u548c\u5e73\u677f\u54cd\u5e94\u5f0f\u7f51\u9875\u8bbe\u8ba1\u3001CMS\u5f8c\u53f0\"><div class='iconbox_icon heading-color avia-svg-icon avia-font-svg_entypo-fontello' data-av_icon='\ue855' data-av_iconfont='entypo-fontello'  ><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >\u7f51\u9875\u8bbe\u8ba1\u3001\u624b\u673a\u548c\u5e73\u677f\u54cd\u5e94\u5f0f\u7f51\u9875\u8bbe\u8ba1\u3001CMS\u5f8c\u53f0<\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/p><\/div>\n<div  class='flex_column av-42d269-e8e9408541924852a769baba6b69692e av_three_fourth  avia-builder-el-7  el_after_av_one_fourth  avia-builder-el-last  flex_column_div  '     ><section  class='av_textblock_section av-30lqzl-9a170c8bf08adebe41145cf8e49091fc '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2>\u4f4f+\u5c45\u5ba4<\/h2>\n<p><a href=\"\/wp-content\/uploads\/webdesignhk-web-design-project-company-website-plan-hongkong-hkdesignweb-interior-website-design.avif\" rel=\"lightbox&#091;auto_group1&#093;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7698\" src=\"\/wp-content\/uploads\/webdesignhk-web-design-project-company-website-plan-hongkong-hkdesignweb-interior-website-design.avif\" alt=\"Living Plus+\" width=\"960\" height=\"554\" \/><\/a><\/p>\n<h3>\u4e3b\u9875<\/h3>\n<p><a href=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_1.avif\" rel=\"lightbox&#091;auto_group1&#093;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_1.avif\" alt=\"Living Plus+\" width=\"960\" height=\"2670\" \/><\/a><\/p>\n<h3>\u516c\u53f8\u80cc\u666f<\/h3>\n<p><a href=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_2.avif\" rel=\"lightbox&#091;auto_group1&#093;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_2.avif\" alt=\"Living Plus+\" width=\"960\" height=\"1172\" \/><\/a><\/p>\n<h3>\u6b27\u6d32\u9762\u6599<\/h3>\n<p><a href=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_3.avif\" rel=\"lightbox&#091;auto_group1&#093;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_3.avif\" alt=\"Living Plus+\" width=\"960\" height=\"1446\" \/><\/a><\/p>\n<h3>\u670d\u52a1\u6982\u89a7<\/h3>\n<p><a href=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_4.avif\" rel=\"lightbox&#091;auto_group1&#093;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_4.avif\" alt=\"Living Plus+\" width=\"960\" height=\"1178\" \/><\/a><\/p>\n<h3>\u516c\u53f8\u52a8\u6001<\/h3>\n<p><a href=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_5.avif\" rel=\"lightbox&#091;auto_group1&#093;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_5.avif\" alt=\"Living Plus+\" width=\"960\" height=\"1345\" \/><\/a><\/p>\n<h3>\u5b8c\u5de5\u9879\u76ee<\/h3>\n<p><a href=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_6.avif\" rel=\"lightbox&#091;auto_group1&#093;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_6.avif\" alt=\"Living Plus+\" width=\"960\" height=\"2323\" \/><\/a><\/p>\n<h3>\u50a2\u4fec\u7cfb\u5217<\/h3>\n<p><a href=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_7.avif\" rel=\"lightbox&#091;auto_group1&#093;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_7.avif\" alt=\"Living Plus+\" width=\"960\" height=\"2398\" \/><\/a><\/p>\n<h3>\u8054\u7edc\u6211\u4eec<\/h3>\n<p><a href=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_8.avif\" rel=\"lightbox&#091;auto_group1&#093;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/website_lp_8.avif\" alt=\"Living Plus+\" width=\"960\" height=\"2844\" \/><\/a><\/p>\n<\/div><\/section><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":7813,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[45,53,52],"class_list":["post-8182","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-45","portfolio_entries-53","portfolio_entries-52"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u4f4f+\u5c45\u5ba4 - \u6e29\u56fd\u4f26\u9999\u6e2f\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8<\/title>\n<meta name=\"description\" content=\"\u9999\u6e2f\u6e29\u56fd\u4f26\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\u662f\u4f4d\u4e8e\u9999\u6e2f\u7684\u4e00\u95f4\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\uff0c\u5728\u9999\u6e2f\u4ece\u4e8b\u4e13\u4e1a CMS \u540e\u53f0\u5185\u5bb9\u7ba1\u7406\u7cfb\u7edf\u7f51\u7ad9\uff0c\u670d\u52a1\u8303\u56f4\u5305\u62ec WordPress\u3001WooCommerce\u3001Joomla\u3001OpenCart \u7f51\u4e0a\u5546\u5e97\u4e0e\u7535\u5b50\u5546\u52a1\u7f51\u5e97\u7cfb\u7edf\u7f51\u9875\u8bbe\u8ba1\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u4f4f+\u5c45\u5ba4 - \u6e29\u56fd\u4f26\u9999\u6e2f\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\" \/>\n<meta property=\"og:description\" content=\"\u9999\u6e2f\u6e29\u56fd\u4f26\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\u662f\u4f4d\u4e8e\u9999\u6e2f\u7684\u4e00\u95f4\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\uff0c\u5728\u9999\u6e2f\u4ece\u4e8b\u4e13\u4e1a CMS \u540e\u53f0\u5185\u5bb9\u7ba1\u7406\u7cfb\u7edf\u7f51\u7ad9\uff0c\u670d\u52a1\u8303\u56f4\u5305\u62ec WordPress\u3001WooCommerce\u3001Joomla\u3001OpenCart \u7f51\u4e0a\u5546\u5e97\u4e0e\u7535\u5b50\u5546\u52a1\u7f51\u5e97\u7cfb\u7edf\u7f51\u9875\u8bbe\u8ba1\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6e29\u56fd\u4f26\u9999\u6e2f\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T18:10:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/sbrand_lp-webdesign.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 \u5206\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u4f4f+\u5c45\u5ba4 - \u6e29\u56fd\u4f26\u9999\u6e2f\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8","description":"\u9999\u6e2f\u6e29\u56fd\u4f26\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\u662f\u4f4d\u4e8e\u9999\u6e2f\u7684\u4e00\u95f4\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\uff0c\u5728\u9999\u6e2f\u4ece\u4e8b\u4e13\u4e1a CMS \u540e\u53f0\u5185\u5bb9\u7ba1\u7406\u7cfb\u7edf\u7f51\u7ad9\uff0c\u670d\u52a1\u8303\u56f4\u5305\u62ec WordPress\u3001WooCommerce\u3001Joomla\u3001OpenCart \u7f51\u4e0a\u5546\u5e97\u4e0e\u7535\u5b50\u5546\u52a1\u7f51\u5e97\u7cfb\u7edf\u7f51\u9875\u8bbe\u8ba1\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/","og_locale":"zh_CN","og_type":"article","og_title":"\u4f4f+\u5c45\u5ba4 - \u6e29\u56fd\u4f26\u9999\u6e2f\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8","og_description":"\u9999\u6e2f\u6e29\u56fd\u4f26\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\u662f\u4f4d\u4e8e\u9999\u6e2f\u7684\u4e00\u95f4\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\uff0c\u5728\u9999\u6e2f\u4ece\u4e8b\u4e13\u4e1a CMS \u540e\u53f0\u5185\u5bb9\u7ba1\u7406\u7cfb\u7edf\u7f51\u7ad9\uff0c\u670d\u52a1\u8303\u56f4\u5305\u62ec WordPress\u3001WooCommerce\u3001Joomla\u3001OpenCart \u7f51\u4e0a\u5546\u5e97\u4e0e\u7535\u5b50\u5546\u52a1\u7f51\u5e97\u7cfb\u7edf\u7f51\u9875\u8bbe\u8ba1\u3002","og_url":"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/","og_site_name":"\u6e29\u56fd\u4f26\u9999\u6e2f\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8","article_modified_time":"2024-09-18T18:10:07+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/sbrand_lp-webdesign.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"3 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/","url":"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/","name":"\u4f4f+\u5c45\u5ba4 - \u6e29\u56fd\u4f26\u9999\u6e2f\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8","isPartOf":{"@id":"https:\/\/hongkongwebdesign.company\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/#primaryimage"},"image":{"@id":"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/#primaryimage"},"thumbnailUrl":"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/sbrand_lp-webdesign.gif","datePublished":"2024-09-01T20:55:17+00:00","dateModified":"2024-09-18T18:10:07+00:00","description":"\u9999\u6e2f\u6e29\u56fd\u4f26\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\u662f\u4f4d\u4e8e\u9999\u6e2f\u7684\u4e00\u95f4\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\uff0c\u5728\u9999\u6e2f\u4ece\u4e8b\u4e13\u4e1a CMS \u540e\u53f0\u5185\u5bb9\u7ba1\u7406\u7cfb\u7edf\u7f51\u7ad9\uff0c\u670d\u52a1\u8303\u56f4\u5305\u62ec WordPress\u3001WooCommerce\u3001Joomla\u3001OpenCart \u7f51\u4e0a\u5546\u5e97\u4e0e\u7535\u5b50\u5546\u52a1\u7f51\u5e97\u7cfb\u7edf\u7f51\u9875\u8bbe\u8ba1\u3002","breadcrumb":{"@id":"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/#primaryimage","url":"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/sbrand_lp-webdesign.gif","contentUrl":"https:\/\/hongkongwebdesign.company\/wp-content\/uploads\/sbrand_lp-webdesign.gif","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/hongkongwebdesign.company\/zh-hans\/web-design-portfolio\/living-plus-web-design\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hongkongwebdesign.company\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"\u4f4f+\u5c45\u5ba4"}]},{"@type":"WebSite","@id":"https:\/\/hongkongwebdesign.company\/#website","url":"https:\/\/hongkongwebdesign.company\/","name":"Addison Wan Hong Kong Web Design Company","description":"\u9999\u6e2f\u6e29\u56fd\u4f26\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\u662f\u4f4d\u4e8e\u9999\u6e2f\u7684\u4e00\u95f4\u7f51\u9875\u8bbe\u8ba1\u516c\u53f8\uff0c\u5728\u9999\u6e2f\u4ece\u4e8b\u4e13\u4e1a CMS \u540e\u53f0\u5185\u5bb9\u7ba1\u7406\u7cfb\u7edf\u7f51\u7ad9\uff0c\u670d\u52a1\u8303\u56f4\u5305\u62ec WordPress\u3001WooCommerce\u3001Joomla\u3001OpenCart \u7f51\u4e0a\u5546\u5e97\u4e0e\u7535\u5b50\u5546\u52a1\u7f51\u5e97\u7cfb\u7edf\u7f51\u9875\u8bbe\u8ba1\u3002","alternateName":"Addison Wan Hong Kong Web Design Company","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hongkongwebdesign.company\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"}]}},"_links":{"self":[{"href":"https:\/\/hongkongwebdesign.company\/zh-hans\/wp-json\/wp\/v2\/portfolio\/8182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hongkongwebdesign.company\/zh-hans\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/hongkongwebdesign.company\/zh-hans\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/hongkongwebdesign.company\/zh-hans\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hongkongwebdesign.company\/zh-hans\/wp-json\/wp\/v2\/comments?post=8182"}],"version-history":[{"count":0,"href":"https:\/\/hongkongwebdesign.company\/zh-hans\/wp-json\/wp\/v2\/portfolio\/8182\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hongkongwebdesign.company\/zh-hans\/wp-json\/wp\/v2\/media\/7813"}],"wp:attachment":[{"href":"https:\/\/hongkongwebdesign.company\/zh-hans\/wp-json\/wp\/v2\/media?parent=8182"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hongkongwebdesign.company\/zh-hans\/wp-json\/wp\/v2\/tags?post=8182"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/hongkongwebdesign.company\/zh-hans\/wp-json\/wp\/v2\/portfolio_entries?post=8182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}